{"id":37422,"date":"2022-07-26T08:49:18","date_gmt":"2022-07-26T08:49:18","guid":{"rendered":"https:\/\/www.caprari.com\/esg\/"},"modified":"2025-10-02T07:54:15","modified_gmt":"2025-10-02T07:54:15","slug":"esg","status":"publish","type":"page","link":"https:\/\/www.caprari.com\/cn\/esg\/","title":{"rendered":"ESG"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;home&#8221; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;padding-6-percent&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; zindex=&#8221;100&#8243; gradient_direction=&#8221;left_t_to_right_b&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;400&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding_tablet=&#8221;40&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; min_width_desktop=&#8221;80vh&#8221; min_width_tablet=&#8221;50vw&#8221; min_width_phone=&#8221;50vw&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][nectar_highlighted_text style=&#8221;text_outline&#8221; outline_thickness=&#8221;regular&#8221; text_outline_color=&#8221;#000000&#8243; text=&#8221;9vh&#8221; custom_font_size=&#8221;8vh&#8221;]\n<h1><strong>Environmental, Social &amp; Governance<\/strong><\/h1>\n[\/nectar_highlighted_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding_tablet=&#8221;0px&#8221; top_padding_phone=&#8221;0px&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; min_width_tablet=&#8221;0px&#8221; min_width_phone=&#8221;0px&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;padding-9-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text]\n<h3>\u6211\u4eec\u81f4\u529b\u4e8e\u5b9e\u73b0\u4e00\u4e2a\u53ef\u6301\u7eed\u7684\u672a\u6765<\/h3>\n[\/vc_column_text][nectar_cta btn_style=&#8221;next-section&#8221; btn_type=&#8221;minimal-arrow&#8221; next_section_color=&#8221;#0a0a0a&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-6&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; min_width_desktop=&#8221;75vw&#8221; min_width_tablet=&#8221;50vw&#8221; min_width_phone=&#8221;50vw&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;3539&#8243; background_image_tablet=&#8221;3813&#8243; background_image_phone=&#8221;3813&#8243; background_image_position=&#8221;left center&#8221; background_image_stacking=&#8221;default&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;ro-reveal-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;75vh&#8221; custom_height_tablet=&#8221;80vh&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;90px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;9%&#8221; bottom_padding=&#8221;6%&#8221; top_padding_tablet=&#8221;8%&#8221; bottom_padding_tablet=&#8221;8%&#8221; top_padding_phone=&#8221;8%&#8221; bottom_padding_phone=&#8221;4%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;home&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;37986&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; zindex=&#8221;100&#8243; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_t_to_right_b&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding_phone=&#8221;8%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1666951543110{margin-bottom: 20px !important;}&#8221;]\n<h3>CAPRARI \u7684\u5546\u4e1a\u6a21\u5f0f\u65e8\u5728\u4e3a\u516c\u53f8\u548c\u5730\u533a\u957f\u671f\u521b\u9020\u53ef\u6301\u7eed\u7684\u5171\u4eab\u4ef7\u503c<\/h3>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding_phone=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text]\u672c\u7740\u9762\u5411\u672a\u6765\u7684\u613f\u666f\uff0c\u6211\u4eec\u63d0\u4f9b\u4e0e\u6c34\u4e16\u754c\u76f8\u5173\u7684\u6838\u5fc3\u4ea7\u54c1\u548c\u670d\u52a1\uff0c\u4ee5\u6700\u9ad8\u7684\u6548\u7387\u6807\u51c6\u4e3a\u4fdd\u969c\uff0c\u65e8\u5728\u6539\u5584\u6211\u4eec\u6240\u7ecf\u8425\u7684\u793e\u533a\u5185\u4eba\u4eec\u548c\u4f01\u4e1a\u7684\u751f\u6d3b\u8d28\u91cf\u3002<\/p>\n<p>CAPRARI \u662f\u4e00\u5bb6\u53ef\u9760\u7684\u4f01\u4e1a\uff0c\u80fd\u591f\u8ddf\u968f\u7740\u884c\u4e1a\u4e0d\u65ad\u53d8\u5316\u7684\u811a\u6b65\u800c\u53d1\u5c55\uff0c\u521b\u9020\u51fa\u4e00\u6761\u6301\u7eed\u589e\u957f\u7684\u9053\u8def\u3002[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;90px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; top_padding_tablet=&#8221;8%&#8221; bottom_padding_tablet=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;home&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; zindex=&#8221;100&#8243; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_t_to_right_b&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1666022054872{margin-bottom: 20px !important;}&#8221;]\n<h3>\u6211\u4eec\u7684\u6218\u7565\u548c ESG \u627f\u8bfa<\/h3>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text]\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>\u6211\u4eec\u7684\u589e\u957f\u6218\u7565\u4e0e\u4e3a\u4eba\u7c7b\u548c\u5730\u7403\u5efa\u7acb\u4e00\u4e2a\u5305\u5bb9\u3001\u53ef\u6301\u7eed\u3001\u6709\u5f39\u6027\u7684\u672a\u6765\u5b8c\u5168\u4e00\u81f4\uff0c\u8fd9\u662f\u8054\u5408\u56fd (UN) \u8981\u901a\u8fc7\u201c17 \u9879\u53ef\u6301\u7eed\u53d1\u5c55\u76ee\u6807\u201d\u5b9e\u73b0\u7684\u76ee\u6807\u3002\u5728 2015 \u5e74 9 \u6708\u7531 193 \u4e2a\u6210\u5458\u56fd\u653f\u5e9c\u7b7e\u7f72\u7684\uff0c\u4f5c\u4e3a\u4eba\u7c7b\u3001\u5730\u7403\u4e0e\u7e41\u8363\u884c\u52a8\u7eb2\u9886\u7684\u300a2030 \u8bae\u7a0b\u300b\u4e2d\u5305\u542b\u4e86\u8fd9\u4e9b\u76ee\u6807\uff1a<\/p>\n<p>\u51e0\u5e74\u6765\uff0c\u6211\u4eec\u4e00\u76f4\u5728\u5b9e\u65bd\u9650\u5236\u73af\u5883\u5f71\u54cd\u7684\u653f\u7b56\uff0c\u5e76\u5728\u6574\u4e2a\u4ef7\u503c\u94fe\u4e2d\u5b9e\u73b0\u793e\u4f1a\u6548\u76ca\u6700\u5927\u5316\u3002\u5177\u4f53\u800c\u8a00\uff0c\u6211\u4eec\u901a\u8fc7\u5b9e\u73b0\u4ea7\u54c1\u548c\u670d\u52a1\uff0c\u8ffd\u6c42\u5b9e\u73b0\u76ee\u6807 2\u30016 \u548c 9\u3002<\/p>\n<p>\u6b64\u5916\uff0c\u4e3a\u4e86\u63d0\u9ad8\u6211\u4eec\u7684\u4e1a\u52a1\u6548\u7387\uff0c\u5e76\u786e\u4fdd\u4e0e\u6240\u6709\u5229\u76ca\u76f8\u5173\u8005\u5efa\u7acb\u7262\u56fa\u548c\u6301\u4e45\u7684\u5173\u7cfb\uff0c\u6211\u4eec\u5b9e\u65bd\u4e86\u4e00\u4e2a\u4e13\u95e8\u7684\u884c\u52a8\u8ba1\u5212\uff0c\u5e76\u5236\u5b9a\u4e86\u5177\u4f53\u7684\u5173\u952e\u7ee9\u6548\u6307\u6807\uff0c\u5bf9\u6b64\u8fdb\u884c\u76d1\u6d4b\u3002<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;7347&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;90px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;9%&#8221; top_padding_tablet=&#8221;8%&#8221; bottom_padding_tablet=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;home&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;85314&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.caprari.com\/wp-content\/uploads\/2025\/09\/Caprari_2025_web_EN.pdf&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; zindex=&#8221;100&#8243; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_t_to_right_b&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1699352361986{margin-bottom: 20px !important;}&#8221;]\n<h3>\u53ef\u6301\u7eed\u53d1\u5c55\u62a5\u544a<\/h3>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text]Caprari \u5c06\u53ef\u6301\u7eed\u53d1\u5c55\u89c6\u4f5c\u4f01\u4e1a\u4ef7\u503c\u89c2\u7684\u5177\u4f53\u4f53\u73b0\uff0c\u4e5f\u662f\u4e0e\u5229\u76ca\u76f8\u5173\u8005\u5efa\u7acb\u4fe1\u5fc3\u548c\u4fe1\u4efb\u5173\u7cfb\u7684\u57fa\u7840\u3002<\/p>\n<p>\u6211\u4eec\u6bcf\u5e74\u90fd\u4f1a\u8d77\u8349\u4e00\u4efd\u300a\u53ef\u6301\u7eed\u53d1\u5c55\u62a5\u544a\u300b\uff0c\u4ee5\u900f\u660e\u7684\u65b9\u5f0f\u6c47\u62a5\u6211\u4eec\u5728\u793e\u4f1a\u3001\u73af\u5883\u548c\u7ecf\u6d4e\u65b9\u9762\u7684\u5404\u9879\u8868\u73b0\u3002\u5bf9\u6240\u6709\u5229\u76ca\u76f8\u5173\u8005\u91c7\u53d6\u900f\u660e\u7684\u6001\u5ea6\u662f\u6307\u5bfc\u6211\u4eec\u516c\u53f8\u6240\u6709\u6d3b\u52a8\u7684\u57fa\u672c\u539f\u5219\uff0c\u4e5f\u6b63\u662f\u51fa\u4e8e\u8fd9\u6837\u7684\u521d\u8877\uff0c\u6211\u4eec\u9009\u62e9\u6bcf\u5e74\u4e3b\u52a8\u8d77\u8349\u4e00\u4efd\u300a\u53ef\u6301\u7eed\u53d1\u5c55\u62a5\u544a\u300b\u3002[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;1vh&#8221;][nectar_btn size=&#8221;medium&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular-tilt&#8221; button_color=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; url=&#8221;https:\/\/www.caprari.com\/wp-content\/uploads\/2025\/09\/Caprari_2025_web_EN.pdf&#8221; text=&#8221;\u70b9\u51fb\u6b64\u5904\u4e0b\u8f7d 2024 \u5e74\u7684\u300a\u53ef\u6301\u7eed\u53d1\u5c55\u62a5\u544a\u300b&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;medium&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular-tilt&#8221; button_color=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; url=&#8221;https:\/\/www.caprari.com\/wp-content\/uploads\/2025\/09\/Caprari-2023-esg-report-ENG.pdf&#8221; text=&#8221;\u70b9\u51fb\u6b64\u5904\u4e0b\u8f7d 2023 \u5e74\u7684\u300a\u53ef\u6301\u7eed\u53d1\u5c55\u62a5\u544a\u300b&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;medium&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular-tilt&#8221; button_color=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; url=&#8221;https:\/\/www.caprari.com\/wp-content\/uploads\/2023\/10\/Caprari-ReportSostenibilita-2022_ENG_web.pdf&#8221; text=&#8221;\u70b9\u51fb\u6b64\u5904\u4e0b\u8f7d 2022 \u5e74\u7684\u300a\u53ef\u6301\u7eed\u53d1\u5c55\u62a5\u544a\u300b&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;90px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f9f9f9&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;9%&#8221; bottom_padding=&#8221;6%&#8221; top_padding_tablet=&#8221;8%&#8221; bottom_padding_tablet=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;home&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; zindex=&#8221;100&#8243; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_t_to_right_b&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1659599079171{margin-bottom: 20px !important;}&#8221;]\n<h3>Rating EcoVadis<\/h3>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text]\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>\u51e0\u5e74\u6765\uff0cCaprari \u4e00\u76f4\u81f4\u529b\u4e8e\u91c7\u53d6\u884c\u52a8\uff0c\u63d0\u9ad8\u4f01\u4e1a\u7ba1\u7406\u7684\u53ef\u6301\u7eed\u6027\u3002\u516c\u53f8\u5728\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb (CSR) \u8bc4\u4f30\u9886\u5bfc\u8005 EcoVadis \u5e73\u53f0\u4e0a\u4e3a\u6240\u91c7\u53d6\u7684\u884c\u52a8\u8fdb\u884c\u4e86\u8ba4\u8bc1\u3002<\/p>\n<p>Ecovadis \u662f\u6700\u91cd\u8981\u7684\u56fd\u9645\u53ef\u6301\u7eed\u53d1\u5c55\u8bc4\u7ea7\u5e73\u53f0\u4e4b\u4e00\uff0c\u7ed9\u51fa\u7684\u5206\u6570\u53cd\u6620\u4e86\u4f01\u4e1a RSI \u7ba1\u7406\u7cfb\u7edf\u7684\u8d28\u91cf\u3002<\/p>\n<p>\u5176\u8bc4\u4f30\u65b9\u6cd5\u662f\u57fa\u4e8e\u56fd\u9645\u6807\u51c6\uff0c\u901a\u8fc7\u56db\u4e2a\u9886\u57df\uff08\u73af\u5883\u3001\u52b3\u5de5\u3001\u4eba\u6743\u3001\u9053\u5fb7\u4e0e\u53ef\u6301\u7eed\u91c7\u8d2d\uff09\u7684 21 \u4e2a\u6307\u6807\u7684\u8868\u73b0\u5f97\u51fa\u3002<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding_phone=&#8221;4%&#8221; bottom_padding_phone=&#8221;4%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;3321&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;90px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; bottom_padding=&#8221;1%&#8221; top_padding_tablet=&#8221;8%&#8221; bottom_padding_tablet=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;home&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221; gradient_type=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1659599226966{margin-bottom: 20px !important;}&#8221;]\n<h3>\u5bf9\u975e\u8425\u5229\u6027\u534f\u4f1a\u7684\u8d44\u52a9<\/h3>\n[\/vc_column_text][vc_column_text]\u591a\u5e74\u6765\uff0cCAPRARI \u4e00\u76f4\u8d44\u52a9\u7740\u51e0\u4e2a\u975e\u8425\u5229\u6027\u534f\u4f1a\uff0c\u76ee\u7684\u662f\u4e3a\u793e\u533a\u63d0\u4f9b\u652f\u6301\u3002\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb\u662f\u516c\u53f8\u7684\u4e00\u4e2a\u5177\u4f53\u7684\u6301\u7eed\u627f\u8bfa\uff0c\u662f\u516c\u53f8\u6218\u7565\u5de5\u4e1a\u53d1\u5c55\u8ba1\u5212\u7684\u4e00\u90e8\u5206\uff0c\u56e0\u4e3a\u6211\u4eec\u53ea\u6709\u56e2\u7ed3\u624d\u80fd\u5efa\u7acb\u8d77\u4e00\u4e2a\u6240\u6709\u5229\u76ca\u76f8\u5173\u8005\u5171\u540c\u53d1\u5c55\u7684\u793e\u4f1a\u3002[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;90px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;column_reverse&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;3%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1666366554713{margin-bottom: 20px !important;}&#8221;]\n<h3>\u8d5e\u6bd4\u4e9a\uff1aMthunzi Centre<\/h3>\n<p>\u996e\u6c34\u662f\u6240\u6709\u4eba\u7684\u6743\u5229[\/vc_column_text][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1666951576008{margin-top: 15px !important;}&#8221; max_width=&#8221;500&#8243;]\u8fd9\u4e2a\u975e\u8425\u5229\u6027\u534f\u4f1a\u6210\u7acb\u4e8e 1995 \u5e74\uff0c\u5728\u80af\u5c3c\u4e9a\u3001\u8d5e\u6bd4\u4e9a\u548c\u82cf\u4e39\u7ecf\u8425\u6536\u5bb9\u6240\u4e0e\u6559\u80b2\u3001\u5b66\u6821\u548c\u804c\u4e1a\u4e2d\u5fc3\u3002CAPRARI \u5728\u8d5e\u6bd4\u4e9a\u7684 Mthunzi Centre \u4e3a\u996e\u7528\u6c34\u7ba1\u7406\u63d0\u4f9b\u6c34\u6cf5\u548c\u63f4\u52a9\u3002\u8fd9\u5bb6\u4e2d\u5fc3\u5bb9\u7eb3\u4e86 60 \u540d\u66fe\u7ecf\u7684\u6d41\u6d6a\u513f\u7ae5\u548c\u5e74\u8f7b\u4eba\uff0c\u4ed6\u4eec\u53ef\u4ee5\u5728\u8fd9\u91cc\u5b66\u4e60\u3001\u4ece\u4e8b\u852c\u83dc\u79cd\u690d\u3001\u517b\u9c7c\u9879\u76ee\uff0c\u8fd8\u53ef\u4ee5\u5230\u88c1\u7f1d\u548c\u6728\u5de5\u8f66\u95f4\u5de5\u4f5c\u3002 Mthunzi Centre \u662f\u7531\u5362\u8428\u5361\u7684 Koinonia \u793e\u533a\u7ba1\u7406\u7684\u4e00\u4e2a\u793e\u4f1a\u6559\u80b2\u9879\u76ee\u3002[\/vc_column_text][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;p&#8221; button_color=&#8221;default&#8221; text_color=&#8221;#000000&#8243; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;\u4e86\u89e3\u8fd9\u4e2a\u9879\u76ee&#8221; url=&#8221;http:\/\/www.amaniforafrica.it\/cosa-facciamo\/mthunzi-centre&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;flickity_static_height_style&#8221; images=&#8221;38021,38020,38022,38032,38033,38034,38035&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;next_prev_arrows_overlaid&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_image&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f9f9f9&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;3%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;101&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;center&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;center&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#95c2e2&#8243; style=&#8221;half_text&#8221;]\n<h2>\u60f3\u8981\u4e86\u89e3\u66f4\u591a\u4fe1\u606f\uff1f<\/h2>\n[\/nectar_highlighted_text][vc_column_text css=&#8221;.vc_custom_1657792991003{margin-top: 15px !important;}&#8221;]\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>\u6211\u4eec\u7684\u56e2\u961f\u968f\u65f6\u606d\u5019\u3002<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular-tilt&#8221; button_color=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; url=&#8221;https:\/\/www.caprari.com\/cn\/%e8%81%94%e7%b3%bb%e6%96%b9%e5%bc%8f\/&#8221; text=&#8221;\u8054\u7cfb\u6211\u4eec&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_contain&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-37422","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESG - Caprari<\/title>\n<meta name=\"description\" content=\"\u4e86\u89e3\u6211\u4eec\u65e8\u5728\u4e3a\u516c\u53f8\u548c\u5f53\u5730\u521b\u9020\u53ef\u6301\u7eed\u4ef7\u503c\u7684\u5546\u4e1a\u6a21\u5f0f\u3002\u6211\u4eec\u603b\u662f\u5c55\u671b\u672a\u6765\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caprari.com\/cn\/esg\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESG - Caprari\" \/>\n<meta property=\"og:description\" content=\"\u4e86\u89e3\u6211\u4eec\u65e8\u5728\u4e3a\u516c\u53f8\u548c\u5f53\u5730\u521b\u9020\u53ef\u6301\u7eed\u4ef7\u503c\u7684\u5546\u4e1a\u6a21\u5f0f\u3002\u6211\u4eec\u603b\u662f\u5c55\u671b\u672a\u6765\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caprari.com\/cn\/esg\/\" \/>\n<meta property=\"og:site_name\" content=\"Caprari\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-02T07:54:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caprari.com\/wp-content\/uploads\/2022\/06\/logo-caprari-def.png\" \/>\n\t<meta property=\"og:image:width\" content=\"304\" \/>\n\t<meta property=\"og:image:height\" content=\"79\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/esg\\\/\",\"url\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/esg\\\/\",\"name\":\"ESG - Caprari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/#website\"},\"datePublished\":\"2022-07-26T08:49:18+00:00\",\"dateModified\":\"2025-10-02T07:54:15+00:00\",\"description\":\"\u4e86\u89e3\u6211\u4eec\u65e8\u5728\u4e3a\u516c\u53f8\u548c\u5f53\u5730\u521b\u9020\u53ef\u6301\u7eed\u4ef7\u503c\u7684\u5546\u4e1a\u6a21\u5f0f\u3002\u6211\u4eec\u603b\u662f\u5c55\u671b\u672a\u6765\u3002\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/esg\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.caprari.com\\\/cn\\\/esg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/esg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/#website\",\"url\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/\",\"name\":\"Caprari\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/#organization\",\"name\":\"Caprari\",\"url\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.caprari.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-caprari-def.png\",\"contentUrl\":\"https:\\\/\\\/www.caprari.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-caprari-def.png\",\"width\":304,\"height\":79,\"caption\":\"Caprari\"},\"image\":{\"@id\":\"https:\\\/\\\/www.caprari.com\\\/cn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESG - Caprari","description":"\u4e86\u89e3\u6211\u4eec\u65e8\u5728\u4e3a\u516c\u53f8\u548c\u5f53\u5730\u521b\u9020\u53ef\u6301\u7eed\u4ef7\u503c\u7684\u5546\u4e1a\u6a21\u5f0f\u3002\u6211\u4eec\u603b\u662f\u5c55\u671b\u672a\u6765\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caprari.com\/cn\/esg\/","og_locale":"zh_CN","og_type":"article","og_title":"ESG - Caprari","og_description":"\u4e86\u89e3\u6211\u4eec\u65e8\u5728\u4e3a\u516c\u53f8\u548c\u5f53\u5730\u521b\u9020\u53ef\u6301\u7eed\u4ef7\u503c\u7684\u5546\u4e1a\u6a21\u5f0f\u3002\u6211\u4eec\u603b\u662f\u5c55\u671b\u672a\u6765\u3002","og_url":"https:\/\/www.caprari.com\/cn\/esg\/","og_site_name":"Caprari","article_modified_time":"2025-10-02T07:54:15+00:00","og_image":[{"width":304,"height":79,"url":"https:\/\/www.caprari.com\/wp-content\/uploads\/2022\/06\/logo-caprari-def.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"3 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.caprari.com\/cn\/esg\/","url":"https:\/\/www.caprari.com\/cn\/esg\/","name":"ESG - Caprari","isPartOf":{"@id":"https:\/\/www.caprari.com\/cn\/#website"},"datePublished":"2022-07-26T08:49:18+00:00","dateModified":"2025-10-02T07:54:15+00:00","description":"\u4e86\u89e3\u6211\u4eec\u65e8\u5728\u4e3a\u516c\u53f8\u548c\u5f53\u5730\u521b\u9020\u53ef\u6301\u7eed\u4ef7\u503c\u7684\u5546\u4e1a\u6a21\u5f0f\u3002\u6211\u4eec\u603b\u662f\u5c55\u671b\u672a\u6765\u3002","breadcrumb":{"@id":"https:\/\/www.caprari.com\/cn\/esg\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caprari.com\/cn\/esg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.caprari.com\/cn\/esg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caprari.com\/cn\/"},{"@type":"ListItem","position":2,"name":"ESG"}]},{"@type":"WebSite","@id":"https:\/\/www.caprari.com\/cn\/#website","url":"https:\/\/www.caprari.com\/cn\/","name":"Caprari","description":"","publisher":{"@id":"https:\/\/www.caprari.com\/cn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caprari.com\/cn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/www.caprari.com\/cn\/#organization","name":"Caprari","url":"https:\/\/www.caprari.com\/cn\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/www.caprari.com\/cn\/#\/schema\/logo\/image\/","url":"https:\/\/www.caprari.com\/wp-content\/uploads\/2022\/06\/logo-caprari-def.png","contentUrl":"https:\/\/www.caprari.com\/wp-content\/uploads\/2022\/06\/logo-caprari-def.png","width":304,"height":79,"caption":"Caprari"},"image":{"@id":"https:\/\/www.caprari.com\/cn\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.caprari.com\/cn\/wp-json\/wp\/v2\/pages\/37422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caprari.com\/cn\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.caprari.com\/cn\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.caprari.com\/cn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caprari.com\/cn\/wp-json\/wp\/v2\/comments?post=37422"}],"version-history":[{"count":11,"href":"https:\/\/www.caprari.com\/cn\/wp-json\/wp\/v2\/pages\/37422\/revisions"}],"predecessor-version":[{"id":85389,"href":"https:\/\/www.caprari.com\/cn\/wp-json\/wp\/v2\/pages\/37422\/revisions\/85389"}],"wp:attachment":[{"href":"https:\/\/www.caprari.com\/cn\/wp-json\/wp\/v2\/media?parent=37422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}