{"id":45323,"date":"2022-08-09T14:23:02","date_gmt":"2022-08-09T14:23:02","guid":{"rendered":"https:\/\/www.caprari.com\/secteur-infrastructures\/"},"modified":"2023-06-28T15:11:39","modified_gmt":"2023-06-28T15:11:39","slug":"secteur-infrastructures","status":"publish","type":"page","link":"https:\/\/www.caprari.com\/tn\/secteur-infrastructures\/","title":{"rendered":"Secteur Infrastructures"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;6204&#8243; bg_image_phone=&#8221;3220&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;20%&#8221; bottom_padding=&#8221;4%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#000000&#8243; color_overlay_2=&#8221;#000000&#8243; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1662392476331{margin-bottom: 30px !important;}&#8221;]\n<h1>Infrastructures<\/h1>\n[\/vc_column_text][nectar_cta btn_style=&#8221;next-section&#8221; btn_type=&#8221;minimal-arrow&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;4%&#8221; top_padding_tablet=&#8221;20%&#8221; bottom_padding_tablet=&#8221;20%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;35&#8243; left_padding_desktop=&#8221;24%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;24%&#8221; bottom_padding_tablet=&#8221;25&#8243; constrain_group_4=&#8221;yes&#8221; left_padding_phone=&#8221;12%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;12%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#000000&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Nos projets&#8221; max_width=&#8221;435&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][nectar_post_grid post_type=&#8221;portfolio&#8221; portfolio_category=&#8221;infrastrutture-tn&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;load-more&#8221; button_color=&#8221;accent-color&#8221; columns=&#8221;4&#8243; grid_item_spacing=&#8221;25px&#8221; grid_item_height=&#8221;30vh&#8221; image_size=&#8221;portfolio-thumb_large&#8221; image_loading=&#8221;lazy-load&#8221; animation=&#8221;fade-in-from-bottom&#8221; heading_tag=&#8221;h4&#8243; enable_indicator=&#8221;yes&#8221; mouse_indicator_style=&#8221;default&#8221; mouse_indicator_text=&#8221;view&#8221; mouse_indicator_color=&#8221;#1a89cc&#8221; mouse_indicator_text_color=&#8221;#ffffff&#8221; category_position=&#8221;default&#8221; grid_style=&#8221;content_overlaid&#8221; text_content_layout=&#8221;all_top_left&#8221; color_overlay=&#8221;#000000&#8243; color_overlay_opacity=&#8221;0.3&#8243; color_overlay_hover_opacity=&#8221;0.4&#8243; text_color=&#8221;light&#8221; text_color_hover=&#8221;light&#8221; text_opacity=&#8221;1&#8243; text_hover_opacity=&#8221;1&#8243; hover_effect=&#8221;none&#8221; border_radius=&#8221;10px&#8221; shadow_on_hover=&#8221;yes&#8221; card_design_bg_color=&#8221;#00cae8&#8243; posts_per_page=&#8221;4&#8243; css_class_name=&#8221;nectar-browser-window-style&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f9f9f9&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; bottom_padding=&#8221;4%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Comment pouvons-nous vous aider ?&#8221; font_container=&#8221;tag:h2|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f9f9f9&#8243; scene_position=&#8221;center&#8221; bottom_padding=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;none&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;linea&#8221; enable_animation=&#8221;true&#8221; animation_speed=&#8221;fast&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; icon_padding=&#8221;0px&#8221; pointer_events=&#8221;all&#8221; icon_linea=&#8221;icon-arrows-question&#8221; icon_size=&#8221;64&#8243; url=&#8221;https:\/\/www.caprari.com\/tn\/faq\/&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h3>FAQ<\/h3>\n<p>Les questions les plus fr\u00e9quemment pos\u00e9es et leurs r\u00e9ponses sur un seul site.[\/vc_column_text][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;p&#8221; button_color=&#8221;default&#8221; button_border_color=&#8221;#1a89cc&#8221; button_border_color_hover=&#8221;#1a89cc&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Pour en savoir plus&#8221; url=&#8221;https:\/\/www.caprari.com\/tn\/faq\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_icon icon_family=&#8221;linea&#8221; enable_animation=&#8221;true&#8221; animation_speed=&#8221;fast&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; icon_padding=&#8221;0px&#8221; pointer_events=&#8221;all&#8221; icon_linea=&#8221;icon-basic-elaboration-mail-star&#8221; animation_delay=&#8221;400&#8243; icon_size=&#8221;64&#8243; url=&#8221;https:\/\/www.caprari.com\/tn\/newsletter\/&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;400&#8243;][vc_column_text]\n<h3>Abonnez-vous \u00e0 la newsletter<\/h3>\n<p>Restez au courant de toutes les actualit\u00e9s du monde de l&#8217;eau.[\/vc_column_text][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;p&#8221; button_color=&#8221;default&#8221; button_border_color=&#8221;#1a89cc&#8221; button_border_color_hover=&#8221;#1a89cc&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Inscrivez-vous&#8221; url=&#8221;https:\/\/www.caprari.com\/tn\/newsletter\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_icon icon_family=&#8221;linea&#8221; enable_animation=&#8221;true&#8221; animation_speed=&#8221;fast&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; icon_padding=&#8221;0px&#8221; pointer_events=&#8221;all&#8221; icon_linea=&#8221;icon-basic-mail-open-text&#8221; animation_delay=&#8221;800&#8243; icon_size=&#8221;64&#8243; url=&#8221;https:\/\/www.caprari.com\/tn\/contacts\/&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;800&#8243; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h3>Vous souhaitez en savoir plus sur les produits ?<\/h3>\n<p>Notre \u00e9quipe est \u00e0 votre enti\u00e8re disposition.[\/vc_column_text][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;p&#8221; button_color=&#8221;default&#8221; button_border_color=&#8221;#1a89cc&#8221; button_border_color_hover=&#8221;#1a89cc&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Contactez-nous&#8221; url=&#8221;https:\/\/www.caprari.com\/tn\/contacts\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;6204&#8243; bg_image_phone=&#8221;3220&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;20%&#8221; bottom_padding=&#8221;4%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#000000&#8243; color_overlay_2=&#8221;#000000&#8243; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-45323","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Secteur Infrastructures - Caprari<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caprari.com\/tn\/secteur-infrastructures\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secteur Infrastructures - Caprari\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;6204&#8243; bg_image_phone=&#8221;3220&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;20%&#8221; bottom_padding=&#8221;4%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#000000&#8243; color_overlay_2=&#8221;#000000&#8243; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caprari.com\/tn\/secteur-infrastructures\/\" \/>\n<meta property=\"og:site_name\" content=\"Caprari\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-28T15:11:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caprari.com\/wp-content\/uploads\/2022\/06\/logo-caprari-def.png\" \/>\n\t<meta property=\"og:image:width\" content=\"304\" \/>\n\t<meta property=\"og:image:height\" content=\"79\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/secteur-infrastructures\\\/\",\"url\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/secteur-infrastructures\\\/\",\"name\":\"Secteur Infrastructures - Caprari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/#website\"},\"datePublished\":\"2022-08-09T14:23:02+00:00\",\"dateModified\":\"2023-06-28T15:11:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/secteur-infrastructures\\\/#breadcrumb\"},\"inLanguage\":\"ar-TN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.caprari.com\\\/tn\\\/secteur-infrastructures\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/secteur-infrastructures\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secteur Infrastructures\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/#website\",\"url\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/\",\"name\":\"Caprari\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar-TN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/#organization\",\"name\":\"Caprari\",\"url\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar-TN\",\"@id\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.caprari.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-caprari-def.png\",\"contentUrl\":\"https:\\\/\\\/www.caprari.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-caprari-def.png\",\"width\":304,\"height\":79,\"caption\":\"Caprari\"},\"image\":{\"@id\":\"https:\\\/\\\/www.caprari.com\\\/tn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secteur Infrastructures - Caprari","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caprari.com\/tn\/secteur-infrastructures\/","og_locale":"ar_AR","og_type":"article","og_title":"Secteur Infrastructures - Caprari","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;6204&#8243; bg_image_phone=&#8221;3220&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;20%&#8221; bottom_padding=&#8221;4%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#000000&#8243; color_overlay_2=&#8221;#000000&#8243; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;...","og_url":"https:\/\/www.caprari.com\/tn\/secteur-infrastructures\/","og_site_name":"Caprari","article_modified_time":"2023-06-28T15:11:39+00:00","og_image":[{"width":304,"height":79,"url":"https:\/\/www.caprari.com\/wp-content\/uploads\/2022\/06\/logo-caprari-def.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.caprari.com\/tn\/secteur-infrastructures\/","url":"https:\/\/www.caprari.com\/tn\/secteur-infrastructures\/","name":"Secteur Infrastructures - Caprari","isPartOf":{"@id":"https:\/\/www.caprari.com\/tn\/#website"},"datePublished":"2022-08-09T14:23:02+00:00","dateModified":"2023-06-28T15:11:39+00:00","breadcrumb":{"@id":"https:\/\/www.caprari.com\/tn\/secteur-infrastructures\/#breadcrumb"},"inLanguage":"ar-TN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caprari.com\/tn\/secteur-infrastructures\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.caprari.com\/tn\/secteur-infrastructures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caprari.com\/tn\/"},{"@type":"ListItem","position":2,"name":"Secteur Infrastructures"}]},{"@type":"WebSite","@id":"https:\/\/www.caprari.com\/tn\/#website","url":"https:\/\/www.caprari.com\/tn\/","name":"Caprari","description":"","publisher":{"@id":"https:\/\/www.caprari.com\/tn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caprari.com\/tn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar-TN"},{"@type":"Organization","@id":"https:\/\/www.caprari.com\/tn\/#organization","name":"Caprari","url":"https:\/\/www.caprari.com\/tn\/","logo":{"@type":"ImageObject","inLanguage":"ar-TN","@id":"https:\/\/www.caprari.com\/tn\/#\/schema\/logo\/image\/","url":"https:\/\/www.caprari.com\/wp-content\/uploads\/2022\/06\/logo-caprari-def.png","contentUrl":"https:\/\/www.caprari.com\/wp-content\/uploads\/2022\/06\/logo-caprari-def.png","width":304,"height":79,"caption":"Caprari"},"image":{"@id":"https:\/\/www.caprari.com\/tn\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.caprari.com\/tn\/wp-json\/wp\/v2\/pages\/45323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caprari.com\/tn\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.caprari.com\/tn\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.caprari.com\/tn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caprari.com\/tn\/wp-json\/wp\/v2\/comments?post=45323"}],"version-history":[{"count":1,"href":"https:\/\/www.caprari.com\/tn\/wp-json\/wp\/v2\/pages\/45323\/revisions"}],"predecessor-version":[{"id":46461,"href":"https:\/\/www.caprari.com\/tn\/wp-json\/wp\/v2\/pages\/45323\/revisions\/46461"}],"wp:attachment":[{"href":"https:\/\/www.caprari.com\/tn\/wp-json\/wp\/v2\/media?parent=45323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}